{"id":15777,"date":"2015-04-24T14:01:39","date_gmt":"2015-04-24T14:01:39","guid":{"rendered":"https:\/\/borges1896.com\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/"},"modified":"2015-04-24T14:01:39","modified_gmt":"2015-04-24T14:01:39","slug":"cambiar-mantequilla-por-aceite-de-oliva","status":"publish","type":"post","link":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/","title":{"rendered":"Cambiar la mantequilla por aceite de oliva"},"content":{"rendered":"<p>Haz la prueba: coge cualquier libro de cocina de casa de abuelos, padres, etc. Si son manuales cl\u00e1sicos de los a\u00f1os 60 o 70, \u00e9poca en la que la cocina francesa dominaba el mundo, habr\u00e1 mantequilla por doquier. Y es que, durante d\u00e9cadas, pocos fueron los que se plantearon que pudiera sustituirse por algo m\u00e1s sano a la hora de meterse entre fogones.<\/p>\n<p>Pues bien, resulta que mientras la mantequilla es rica en grasas saturadas,\u00a0 el aceite lo es en \u00e1cidos grasos monoinsaturados, que son los m\u00e1s sencillos de asimilar por nuestro organismo. Adem\u00e1s, el aceite de oliva extra contiene polifenoles adem\u00e1s de virtudes a\u00f1adidas como su capacidad de mejorar la circulaci\u00f3n o de mejorar la funci\u00f3n intestinal.<\/p>\n<p>A continuaci\u00f3n, y sin \u00e1nimo de corregir a los libros hist\u00f3ricos de recetas (bueno, un poco s\u00ed, para qu\u00e9 lo vamos a negar&#8230;), repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva. Siempre teniendo en cuenta, eso s\u00ed, que una medida de mantequilla equivale a \u00be partes de aceite.<\/p>\n<p><b>Bizcocho.<\/b> Un dulce tan popular como \u00e9ste es mucho m\u00e1s saludable si empleamos el aceite como \u00fanica grasa. Queda tan esponjoso como con mantequilla y, adem\u00e1s, podemos usar el aceite para engrasar el molde y que no se nos pegue.<\/p>\n<p><b>Risotto.<\/b> Aunque a los italianos no les va eso de modificar, aunque sea m\u00ednimamente, sus recetas m\u00e1s tradicionales, hay que decir que no son pocos los que \u00faltimamente, y en aras de una dieta m\u00e1s saludable, \u201cpermiten\u201d cambiar la mantequilla por el aceite de oliva virgen extra en un risotto. Muchos ya hab\u00edamos prescindido de ella antes, conformes con el efecto que consegu\u00edamos a\u00f1adiendo \u00fanicamente parmesano al final.<\/p>\n<p><strong>S\u00e1ndwich de jam\u00f3n y queso.<\/strong> Tras una infancia en la que nos pasamos untando de mantequilla rebanadas de pan de molde, llega un momento en la vida en la que descubrimos que podemos hacer lo mismo con aceite de oliva. Prueba: coge un pincel y unta con un poco de aceite las dos <i>tapas<\/i> de tu s\u00e1ndwich de jam\u00f3n y queso. Se tostar\u00e1 en la sart\u00e9n igual de bien que con la mantequilla.<\/p>\n<p><b>Magdalenas.<\/b> Otro postre que, como el bizcocho, no sufre demasiadas variaciones si sacamos la mantequilla. El aceite de oliva, dependiendo de la variedad, aporta adem\u00e1s toques arom\u00e1ticos que pueden hacer nuestras magdalenas una aut\u00e9ntica delicatesen.<\/p>\n<p><b>Pur\u00e9s.<\/b> No somos pocos los que arqueamos la ceja cuando, en una receta de pur\u00e9 o crema, nos topamos con mantequilla. No, no y no. El aceite de oliva convierte cualquier crema en una opci\u00f3n ligera y nutritiva y aporta toda la grasa que un plato as\u00ed necesita.<\/p>\n<p><b>Masa de pan (o de pizza).<\/b> El aceite de oliva, en este caso, no es solo un aliado para que la masa resulte menos pesada, sino que, adem\u00e1s, evita que nuestro pan o nuestra pizza acaben convirti\u00e9ndose en una pieza de boller\u00eda industrial.<\/p>\n<p><b>Bechamel.<\/b> \u00a1Ojito, porque aqu\u00ed estamos tocando una receta cl\u00e1sica francesa! Si ponemos aceite en lugar de mantequilla, quiz\u00e1 la salsa acabe teniendo un color m\u00e1s oscuro. Tambi\u00e9n puede ser que el sabor sea ligeramente m\u00e1s potente, aunque esto no tiene por qu\u00e9 ser un problema: es m\u00e1s, puede llegar a ser incluso una ventaja.<\/p>\n<p><b>Tostada del desayuno.<\/b> Todos los beneficios del aceite que ya hemos enumerado al principio del art\u00edculo sirven aqu\u00ed para justificar por qu\u00e9 es buena idea cambiar la tostada del desayuno con mantequilla y mermelada por una con aceite y sal. Aqu\u00ed el resultado no se parece en nada, as\u00ed que se trata de elegir. Quiz\u00e1 el a\u00f1adido de un poco de tomate o de una loncha de jam\u00f3n ib\u00e9rico acabe de ayudar a los indecisos\u2026<\/p>\n<p><b>Pasteles de pescado. <\/b>La idea de preparar un pastel de pescado es hacer un plato con todos los beneficios de, por ejemplo, un pescado azul. Es posible que haya que utilizar nata para conseguir una textura y consistencia determinadas, pero la mantequilla puede reemplazarse sin problema por aceite de oliva. Aviso: este cambio, igual que los anteriores, no tiene vuelta atr\u00e1s. O eso creemos nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.<\/p>\n","protected":false},"author":2,"featured_media":14369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambiar la mantequilla por aceite de oliva - Borges<\/title>\n<meta name=\"description\" content=\"Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambiar la mantequilla por aceite de oliva - Borges\" \/>\n<meta property=\"og:description\" content=\"Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/\" \/>\n<meta property=\"og:site_name\" content=\"Borges\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-24T14:01:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/FOTO_20150423-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"849\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mortensen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mortensen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/\"},\"author\":{\"name\":\"mortensen\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"headline\":\"Cambiar la mantequilla por aceite de oliva\",\"datePublished\":\"2015-04-24T14:01:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/\"},\"wordCount\":732,\"image\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/FOTO_20150423-1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/\",\"url\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/\",\"name\":\"Cambiar la mantequilla por aceite de oliva - Borges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/FOTO_20150423-1.jpg\",\"datePublished\":\"2015-04-24T14:01:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"description\":\"Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/FOTO_20150423-1.jpg\",\"contentUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/FOTO_20150423-1.jpg\",\"width\":849,\"height\":566},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/cambiar-mantequilla-por-aceite-de-oliva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/borges1896.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambiar la mantequilla por aceite de oliva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/borges1896.com\\\/es\\\/\",\"name\":\"Borges\",\"description\":\"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\",\"name\":\"mortensen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"caption\":\"mortensen\"},\"url\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/author\\\/mortensen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambiar la mantequilla por aceite de oliva - Borges","description":"Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/","og_locale":"es_ES","og_type":"article","og_title":"Cambiar la mantequilla por aceite de oliva - Borges","og_description":"Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.","og_url":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/","og_site_name":"Borges","article_published_time":"2015-04-24T14:01:39+00:00","og_image":[{"width":849,"height":566,"url":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/FOTO_20150423-1.jpg","type":"image\/jpeg"}],"author":"mortensen","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mortensen","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#article","isPartOf":{"@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/"},"author":{"name":"mortensen","@id":"https:\/\/borges1896.com\/es\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"headline":"Cambiar la mantequilla por aceite de oliva","datePublished":"2015-04-24T14:01:39+00:00","mainEntityOfPage":{"@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/"},"wordCount":732,"image":{"@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/FOTO_20150423-1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/","url":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/","name":"Cambiar la mantequilla por aceite de oliva - Borges","isPartOf":{"@id":"https:\/\/borges1896.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#primaryimage"},"image":{"@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/FOTO_20150423-1.jpg","datePublished":"2015-04-24T14:01:39+00:00","author":{"@id":"https:\/\/borges1896.com\/es\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"description":"Repasamos una serie de recetas en las que toda la vida hemos usado mantequilla y en las que \u00a1s\u00ed, se puede! reemplazar por aceite de oliva virgen extra.","breadcrumb":{"@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#primaryimage","url":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/FOTO_20150423-1.jpg","contentUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/FOTO_20150423-1.jpg","width":849,"height":566},{"@type":"BreadcrumbList","@id":"https:\/\/borges1896.com\/es\/blog\/cambiar-mantequilla-por-aceite-de-oliva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/borges1896.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cambiar la mantequilla por aceite de oliva"}]},{"@type":"WebSite","@id":"https:\/\/borges1896.com\/es\/#website","url":"https:\/\/borges1896.com\/es\/","name":"Borges","description":"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/borges1896.com\/es\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60","name":"mortensen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","caption":"mortensen"},"url":"https:\/\/borges1896.com\/es\/blog\/author\/mortensen\/"}]}},"_links":{"self":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/posts\/15777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/comments?post=15777"}],"version-history":[{"count":0,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/posts\/15777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/media\/14369"}],"wp:attachment":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/media?parent=15777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/categories?post=15777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/tags?post=15777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}