{"id":15933,"date":"2016-11-09T11:35:48","date_gmt":"2016-11-09T11:35:48","guid":{"rendered":"https:\/\/borges1896.com\/blog\/la-autentica-carbonara\/"},"modified":"2016-11-09T11:35:48","modified_gmt":"2016-11-09T11:35:48","slug":"la-autentica-carbonara","status":"publish","type":"post","link":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/","title":{"rendered":"C\u00f3mo preparar una aut\u00e9ntica carbonara"},"content":{"rendered":"<p>Pasta, <em>guanciale<\/em> (una especie de panceta), yemas de huevo, queso pecorino y pimienta negra. La aut\u00e9ntica receta carbonara tiene estos ingredientes y, como puedes comprobar, la nata no es ninguno de ellos. Una de las m\u00e1s famosas recetas del Lazio consigue esa \u00absalsa\u00bb de cremosa textura a base de: yemas de huevo, sal, pimienta y pecorino romano. Una mezcla que se incorpora siempre fuera del fuego y que se \u00abcocina\u00bb al calor de la propia pasta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pasta, guanciale (una especie de panceta), yemas de huevo, queso pecorino y pimienta negra. La aut\u00e9ntica receta carbonara tiene estos&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo preparar una aut\u00e9ntica carbonara - Borges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo preparar una aut\u00e9ntica carbonara - Borges\" \/>\n<meta property=\"og:description\" content=\"Pasta, guanciale (una especie de panceta), yemas de huevo, queso pecorino y pimienta negra. La aut\u00e9ntica receta carbonara tiene estos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/\" \/>\n<meta property=\"og:site_name\" content=\"Borges\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-09T11:35:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/TRUC-20161109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mortensen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mortensen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/\"},\"author\":{\"name\":\"mortensen\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"headline\":\"C\u00f3mo preparar una aut\u00e9ntica carbonara\",\"datePublished\":\"2016-11-09T11:35:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/\"},\"wordCount\":85,\"image\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/TRUC-20161109.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/\",\"url\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/\",\"name\":\"C\u00f3mo preparar una aut\u00e9ntica carbonara - Borges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/TRUC-20161109.jpg\",\"datePublished\":\"2016-11-09T11:35:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/TRUC-20161109.jpg\",\"contentUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2021\\\/06\\\/TRUC-20161109.jpg\",\"width\":848,\"height\":566,\"caption\":\"Borges - La aut\u00e9ntica carbonara\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/la-autentica-carbonara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/borges1896.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo preparar una aut\u00e9ntica carbonara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/borges1896.com\\\/es\\\/\",\"name\":\"Borges\",\"description\":\"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borges1896.com\\\/es\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\",\"name\":\"mortensen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"caption\":\"mortensen\"},\"url\":\"https:\\\/\\\/borges1896.com\\\/es\\\/blog\\\/author\\\/mortensen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo preparar una aut\u00e9ntica carbonara - Borges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo preparar una aut\u00e9ntica carbonara - Borges","og_description":"Pasta, guanciale (una especie de panceta), yemas de huevo, queso pecorino y pimienta negra. La aut\u00e9ntica receta carbonara tiene estos...","og_url":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/","og_site_name":"Borges","article_published_time":"2016-11-09T11:35:48+00:00","og_image":[{"width":848,"height":566,"url":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/TRUC-20161109.jpg","type":"image\/jpeg"}],"author":"mortensen","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mortensen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#article","isPartOf":{"@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/"},"author":{"name":"mortensen","@id":"https:\/\/borges1896.com\/es\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"headline":"C\u00f3mo preparar una aut\u00e9ntica carbonara","datePublished":"2016-11-09T11:35:48+00:00","mainEntityOfPage":{"@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/"},"wordCount":85,"image":{"@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/TRUC-20161109.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/","url":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/","name":"C\u00f3mo preparar una aut\u00e9ntica carbonara - Borges","isPartOf":{"@id":"https:\/\/borges1896.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#primaryimage"},"image":{"@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/TRUC-20161109.jpg","datePublished":"2016-11-09T11:35:48+00:00","author":{"@id":"https:\/\/borges1896.com\/es\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"breadcrumb":{"@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#primaryimage","url":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/TRUC-20161109.jpg","contentUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2021\/06\/TRUC-20161109.jpg","width":848,"height":566,"caption":"Borges - La aut\u00e9ntica carbonara"},{"@type":"BreadcrumbList","@id":"https:\/\/borges1896.com\/es\/blog\/la-autentica-carbonara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/borges1896.com\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo preparar una aut\u00e9ntica carbonara"}]},{"@type":"WebSite","@id":"https:\/\/borges1896.com\/es\/#website","url":"https:\/\/borges1896.com\/es\/","name":"Borges","description":"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/borges1896.com\/es\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60","name":"mortensen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","caption":"mortensen"},"url":"https:\/\/borges1896.com\/es\/blog\/author\/mortensen\/"}]}},"_links":{"self":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/posts\/15933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/comments?post=15933"}],"version-history":[{"count":0,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/posts\/15933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/media\/15934"}],"wp:attachment":[{"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/media?parent=15933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/categories?post=15933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borges1896.com\/es\/wp-json\/wp\/v2\/tags?post=15933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}